{"id":1440,"date":"2021-11-30T23:32:36","date_gmt":"2021-11-30T23:32:36","guid":{"rendered":"https:\/\/costaricatraveland.com\/?page_id=1440"},"modified":"2025-11-13T01:04:51","modified_gmt":"2025-11-13T01:04:51","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/","title":{"rendered":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1440\" class=\"elementor elementor-1440\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc4d354 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"fc4d354\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9449bdf\" data-id=\"9449bdf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b544e4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4b544e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;motion_fx_blur_direction&quot;:&quot;in-out&quot;,&quot;motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:75,&quot;end&quot;:100}},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9rminos y Condiciones de Traveland | Reservas Confiables<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcfa464 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcfa464\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5482c9c\" data-id=\"5482c9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dba828e elementor-widget elementor-widget-text-editor\" data-id=\"dba828e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><strong>Pol\u00edtica de pagos y cancelaciones:<\/strong><\/h1><p>Podemos aceptar un dep\u00f3sito del 10% para reservar su viaje y el resto 45 d\u00edas antes de la llegada mediante tarjeta de cr\u00e9dito o transferencia bancaria.<\/p><p>Los dep\u00f3sitos no son reembolsables, pero pueden aplicarse a un viaje futuro en caso de cancelaci\u00f3n. Si el cliente cancela su reserva 45 d\u00edas o m\u00e1s antes del 1er d\u00eda de viaje, se le reembolsar\u00e1 el 10% del precio del paquete (45-30 d\u00edas = 50%, 30-15 d\u00edas = 25%, menos de 15 d\u00edas = sin reembolso). Las partes del itinerario que no se presenten o no se utilicen no son reembolsables.<\/p><p> <\/p><h1><strong>Descargo de responsabilidad:<\/strong><\/h1><p>La informaci\u00f3n de nuestro sitio web y los datos que encontrar\u00e1 se han recopilado con cuidado y se facilitan de buena fe. Sin embargo, est\u00e1 sujeta a cambios y no forma parte del contrato entre el cliente y Traveland Costa Rica. Si hay alg\u00fan cambio debido a mejoras de viajeros anteriores, comentarios y nuestra propia investigaci\u00f3n, haremos ajustes, pero siempre garantizamos que recibir\u00e1 lo que ha pagado. Nuestro objetivo es ofrecerle la mejor experiencia posible. Nuestra intenci\u00f3n es ce\u00f1irnos a las rutas descritas, pero existe cierta flexibilidad en los itinerarios y, en ocasiones, puede ser necesario o conveniente realizar modificaciones. Los itinerarios son breves, ya que nunca sabemos exactamente ad\u00f3nde nos llevar\u00e1 nuestro viaje. Debido a nuestro estilo de viajar y a las regiones que visitamos, los viajes pueden ser imprevisibles. La informaci\u00f3n que figura en nuestro sitio web es una gu\u00eda general del viaje y de la regi\u00f3n, y cualquier menci\u00f3n de destinos o fauna espec\u00edficos no garantiza en modo alguno que vayan a visitarse o encontrarse. Los viajes de expedici\u00f3n a bordo y las visitas a estaciones de investigaci\u00f3n dependen del permiso final. Adem\u00e1s, los tiempos de viaje indicados son aproximados y est\u00e1n sujetos a cambios debidos a circunstancias locales. Traveland Costa Rica mantiene comunicaci\u00f3n con nuestros proveedores (socios) y se asegura de llevar siempre la informaci\u00f3n m\u00e1s actualizada sobre ellos. Tambi\u00e9n realizamos visitas e inspecciones frecuentes para asegurarnos de que el servicio prestado es el que queremos ofrecerle. Traveland Costa Rica y todos los proveedores (socios) cuentan con un seguro de responsabilidad civil. La mayor\u00eda de los gu\u00edas y conductores est\u00e1n formados en primeros auxilios\/RCP en caso de emergencia. No obstante, le recomendamos encarecidamente que tenga su propio seguro de viaje con una compa\u00f1\u00eda acreditada antes de venir a nuestro pa\u00eds. Traveland Costa Rica no asume ninguna responsabilidad por lesiones, p\u00e9rdidas o da\u00f1os a personas o propiedades en conexi\u00f3n con cualquier servicio que resulte directamente de actos de la naturaleza, huelgas, disturbios civiles, restricciones o regulaciones gubernamentales, discrepancias o cambios en el tr\u00e1nsito.<\/p><p> <\/p><p>Relacionados con los servicios que comercializamos:<\/p><p> <\/p><h3>Excursiones y actividades:<\/h3><p>Estamos orgullosos de asociarnos con los mejores Tour Operadores de Costa Rica. Hemos buscado a los pioneros, a los que ofrecen las mejores actividades, y hemos reunido para ti a los proveedores m\u00e1s divertidos, seguros, profesionales y responsables.<\/p><p> <\/p><h3>Transporte y traslados:<\/h3><p>Las empresas de transporte que utilizamos tienen licencia y experiencia. Podemos organizar los siguientes tipos de traslados: Lanzaderas compartidas, Minibuses privados, Autobuses, Coches de alquiler y Barcos. Tambi\u00e9n vuelos nacionales dentro del pa\u00eds.<\/p><p> <\/p><h3>Alojamiento:<\/h3><p>Con tantas opciones diferentes de alojamiento en Costa Rica, podemos ofrecer opciones desde Hostales, Hoteles y Todo Incluido. Costa Rica es un pa\u00eds en v\u00edas de desarrollo, por lo que agradecemos su paciencia y comprensi\u00f3n en caso de que se produzca alg\u00fan incidente, como falta de agua caliente o cortes de electricidad.<\/p><p> <\/p><h3>Nuestro servicio de agencia de viajes:<\/h3><p>Es un placer para nosotros ofrecerle un servicio de la m\u00e1s alta calidad a lo largo de su experiencia con nosotros. Perm\u00edtanos ayudarle a planificar su viaje a Costa Rica. Viaje con cuidado y disfrute.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-345683f elementor-section-full_width planyourtripcontainer elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"345683f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;opacity-tilt&quot;,&quot;shape_divider_bottom&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d45b66\" data-id=\"7d45b66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4676f0c elementor-cta--skin-cover elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"4676f0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/09\/Surfing-at-Santa-Teresa-1536x954.jpg);\" role=\"img\" aria-label=\"Surfing-at-Santa-Teresa\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--shrink\">\n\t\t\t\t\t\t\u00a1Planifique su viaje!\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--shrink\">\n\t\t\t\t\t\tAhorre tiempo y dinero y aseg\u00farese de disfrutar al m\u00e1ximo de Costa Rica con nosotros.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--shrink\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-md\" href=\"https:\/\/costaricatraveland.com\/planifique-sus-vacaciones\/\">\n\t\t\t\t\t\t\u00a1Vamos!\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En Costa Rica Travel &#038; queremos que planifiques tu viaje con total confianza.<br \/>\nConsulta aqu\u00ed los t\u00e9rminos y condiciones de viaje, pol\u00edticas de cancelaci\u00f3n, uso del sitio y detalles de nuestras reservas para disfrutar unas vacaciones seguras, claras y sin preocupaciones.<br \/>\nTransparencia y compromiso son la base de cada experiencia que creamos para ti en Costa Rica.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","_angie_page":false,"inline_featured_image":false,"_joinchat":[],"footnotes":""},"class_list":["post-1440","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Conoce los t\u00e9rminos y condiciones de viaje con Costa Rica Travel &amp;. Reserva con confianza y vive experiencias sin contratiempos.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Costa Rica Traveland - Costa Rica Travel Agency\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables\" \/>\n\t\t<meta property=\"og:description\" content=\"Conoce los t\u00e9rminos y condiciones de viaje con Costa Rica Travel &amp;. Reserva con confianza y vive experiencias sin contratiempos.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-11-30T23:32:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-13T01:04:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelandcostarica\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Conoce los t\u00e9rminos y condiciones de viaje con Costa Rica Travel &amp;. Reserva con confianza y vive experiencias sin contratiempos.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/terminos-y-condiciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/terminos-y-condiciones\\\/#listItem\",\"name\":\"T\\u00e9rminos y Condiciones de Traveland | Reservas Confiables\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/terminos-y-condiciones\\\/#listItem\",\"position\":2,\"name\":\"T\\u00e9rminos y Condiciones de Traveland | Reservas Confiables\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#organization\",\"name\":\"Costa Rica Traveland\",\"description\":\"Costa Rica Travel Agency\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/\",\"telephone\":\"+50640001623\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-green-no-cr-registered2-1.png\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/terminos-y-condiciones\\\/#organizationLogo\",\"width\":1366,\"height\":768},\"image\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/terminos-y-condiciones\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/travelandcostarica\",\"https:\\\/\\\/www.instagram.com\\\/travelandcostarica\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CostaRicaTraveland\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/terminos-y-condiciones\\\/#webpage\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/terminos-y-condiciones\\\/\",\"name\":\"T\\u00e9rminos y Condiciones de Traveland | Reservas Confiables\",\"description\":\"Conoce los t\\u00e9rminos y condiciones de viaje con Costa Rica Travel &. Reserva con confianza y vive experiencias sin contratiempos.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/terminos-y-condiciones\\\/#breadcrumblist\"},\"datePublished\":\"2021-11-30T23:32:36+00:00\",\"dateModified\":\"2025-11-13T01:04:51+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/\",\"name\":\"Costa Rica Traveland\",\"description\":\"Costa Rica Travel Agency\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables","description":"Conoce los t\u00e9rminos y condiciones de viaje con Costa Rica Travel &. Reserva con confianza y vive experiencias sin contratiempos.","canonical_url":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/costaricatraveland.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/#listItem","name":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables"}},{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/#listItem","position":2,"name":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables","previousItem":{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/costaricatraveland.com\/es\/#organization","name":"Costa Rica Traveland","description":"Costa Rica Travel Agency","url":"https:\/\/costaricatraveland.com\/es\/","telephone":"+50640001623","logo":{"@type":"ImageObject","url":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png","@id":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/#organizationLogo","width":1366,"height":768},"image":{"@id":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/travelandcostarica","https:\/\/www.instagram.com\/travelandcostarica\/","https:\/\/www.youtube.com\/@CostaRicaTraveland"]},{"@type":"WebPage","@id":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/#webpage","url":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/","name":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables","description":"Conoce los t\u00e9rminos y condiciones de viaje con Costa Rica Travel &. Reserva con confianza y vive experiencias sin contratiempos.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/costaricatraveland.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/#breadcrumblist"},"datePublished":"2021-11-30T23:32:36+00:00","dateModified":"2025-11-13T01:04:51+00:00"},{"@type":"WebSite","@id":"https:\/\/costaricatraveland.com\/es\/#website","url":"https:\/\/costaricatraveland.com\/es\/","name":"Costa Rica Traveland","description":"Costa Rica Travel Agency","inLanguage":"es-ES","publisher":{"@id":"https:\/\/costaricatraveland.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Costa Rica Traveland - Costa Rica Travel Agency","og:type":"article","og:title":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables","og:description":"Conoce los t\u00e9rminos y condiciones de viaje con Costa Rica Travel &amp;. Reserva con confianza y vive experiencias sin contratiempos.","og:url":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/","og:image":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png","og:image:secure_url":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png","og:image:width":1366,"og:image:height":768,"article:published_time":"2021-11-30T23:32:36+00:00","article:modified_time":"2025-11-13T01:04:51+00:00","article:publisher":"https:\/\/www.facebook.com\/travelandcostarica","twitter:card":"summary","twitter:title":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables","twitter:description":"Conoce los t\u00e9rminos y condiciones de viaje con Costa Rica Travel &amp;. Reserva con confianza y vive experiencias sin contratiempos.","twitter:image":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png"},"aioseo_meta_data":{"post_id":"1440","title":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables","description":"Conoce los t\u00e9rminos y condiciones de viaje con Costa Rica Travel &amp;. Reserva con confianza y vive experiencias sin contratiempos.","keywords":null,"keyphrases":{"focus":{"keyphrase":"t\u00e9rminos y condiciones","score":64,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":4},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[],"defaultGraph":"WebPage","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2021-11-30 23:32:41","updated":"2025-11-13 01:05:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/costaricatraveland.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tT\u00e9rminos y Condiciones de Traveland | Reservas Confiables\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/costaricatraveland.com\/es\/"},{"label":"T\u00e9rminos y Condiciones de Traveland | Reservas Confiables","link":"https:\/\/costaricatraveland.com\/es\/terminos-y-condiciones\/"}],"_links":{"self":[{"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/pages\/1440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/comments?post=1440"}],"version-history":[{"count":5,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/pages\/1440\/revisions"}],"predecessor-version":[{"id":12332,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/pages\/1440\/revisions\/12332"}],"wp:attachment":[{"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/media?parent=1440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}