{"id":6508,"date":"2023-09-21T21:45:35","date_gmt":"2023-09-21T21:45:35","guid":{"rendered":"https:\/\/costaricatraveland.com\/activities\/excursion-nocturna-a-el-refugio\/"},"modified":"2023-11-20T19:32:18","modified_gmt":"2023-11-20T19:32:18","slug":"excursion-nocturna-a-el-refugio","status":"publish","type":"activities","link":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/","title":{"rendered":"Excursi\u00f3n nocturna a El Refugio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6508\" class=\"elementor elementor-6508 elementor-4593\" data-elementor-post-type=\"activities\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77226006 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77226006\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-66b7602d\" data-id=\"66b7602d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c235cf3 elementor-widget elementor-widget-heading\" data-id=\"6c235cf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Excursi\u00f3n nocturna a El Refugio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-47b12eea\" data-id=\"47b12eea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-71b31a24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71b31a24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-110bdf8e\" data-id=\"110bdf8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32f2406d elementor-widget elementor-widget-gallery\" data-id=\"32f2406d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:3,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;columns_mobile&quot;:3,&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/07\/El-Refugio-Night-Tour-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIxMiwidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA3XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItMS5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/07\/El-Refugio-Night-Tour-1-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIxNSwidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA4XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItMi5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-2-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIxNywidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA4XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItMy5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-3-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIxOSwidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA4XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItNC5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-4-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIyMSwidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA4XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItNS5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-5-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIyMywidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA4XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItNi5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-6-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-7.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIyNSwidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA4XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItNy5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-7-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-8.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIyNywidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA4XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItOC5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-8-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-9.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"32f2406d\" data-elementor-lightbox-title=\"El Refugio Night Tour - 9\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIyOSwidXJsIjoiaHR0cHM6XC9cL2Nvc3RhcmljYXRyYXZlbGFuZC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA4XC9FbC1SZWZ1Z2lvLU5pZ2h0LVRvdXItOS5qcGciLCJzbGlkZXNob3ciOiIzMmYyNDA2ZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/08\/El-Refugio-Night-Tour-9-800x533.webp\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4de733a9 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4de733a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-49ee89bc\" data-id=\"49ee89bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bc987e5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2bc987e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Monteverde<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2101b91d\" data-id=\"2101b91d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5357f337 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5357f337\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Santuario de animales<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7087725\" data-id=\"7087725\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5accd1b3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5accd1b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Naturaleza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-242072cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"242072cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c8bed37\" data-id=\"7c8bed37\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a1c2cbb elementor-widget elementor-widget-text-editor\" data-id=\"5a1c2cbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros.\n\nLos animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno.  \n\nEl Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona.  \n\nTe unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n.\n\nRestricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.  \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-471d57c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"471d57c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2365b248\" data-id=\"2365b248\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-324437f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"324437f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-43e3be9d\" data-id=\"43e3be9d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-474e722a elementor-widget elementor-widget-heading\" data-id=\"474e722a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 incluye?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ed4b829 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ed4b829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Transporte (adicional)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-ticket-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entrada<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gu\u00eda<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67587001\" data-id=\"67587001\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5395da6 elementor-widget elementor-widget-heading\" data-id=\"5395da6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 hay que saber?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bdea4b3 elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4bdea4b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n          <b>Salida:  <\/b>\n        18:00 - 20:00<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n          <b>Vuelve:  <\/b>\n        20:00 - 22:00<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n          <b>Duraci\u00f3n:  <\/b>\n        2 horas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n          <b>Min. Pax:  <\/b>\n        2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n          <b>Edades:  <\/b>\n        4+<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55380620 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55380620\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-56513908\" data-id=\"56513908\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14f7f083 elementor-widget elementor-widget-heading\" data-id=\"14f7f083\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recomendaciones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-549dcdce elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"549dcdce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Calzado cerrado o zapatillas de agua, si lo prefiere.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ropa c\u00f3moda y ligera, mejor si es transpirable.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chaqueta o chubasquero, por si aparece una lluvia amiga.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Conviene llevar crema solar y repelente de insectos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">C\u00e1mara y funda impermeable para tel\u00e9fono<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-17ee732f\" data-id=\"17ee732f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-509a0164 elementor-widget elementor-widget-heading\" data-id=\"509a0164\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Precios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a7a94f3 elementor-widget elementor-widget-heading\" data-id=\"4a7a94f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Internacional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa19419 elementor-widget elementor-widget-text-editor\" data-id=\"3fa19419\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span class=\"pricing-highlight-content\">Adultos:<\/span> $35\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72a6ddd5 elementor-widget elementor-widget-text-editor\" data-id=\"72a6ddd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span class=\"pricing-highlight-content\">Ni\u00f1os:<\/span> $29\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bb7be11 elementor-widget elementor-widget-heading\" data-id=\"1bb7be11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Local<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a8a2d89 elementor-widget elementor-widget-text-editor\" data-id=\"1a8a2d89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span class=\"pricing-highlight-content\">Adultos:<\/span> $27\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70ae509a elementor-widget elementor-widget-text-editor\" data-id=\"70ae509a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span class=\"pricing-highlight-content\">Ni\u00f1os:<\/span> $27\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-331d350f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"331d350f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6474a324\" data-id=\"6474a324\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44eaed4a elementor-widget elementor-widget-text-editor\" data-id=\"44eaed4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>* Los precios reflejan nuestra mejor aproximaci\u00f3n a las tarifas de temporada baja y alta y est\u00e1n sujetos a cambios en cualquier momento. Recibir\u00e1 un precio 100% exacto cuando se informe con nosotros. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-238dfd5b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"238dfd5b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a524e21\" data-id=\"5a524e21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d1f4e02 elementor-widget elementor-widget-heading\" data-id=\"4d1f4e02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formulario de consulta<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e487801 elementor-widget elementor-widget-shortcode\" data-id=\"e487801\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n          <iframe aria-label=\"Activity Form\" frameborder=\"0\" style=\"height:1550px;width:99%;border:none;\" src=\"https:\/\/forms.zohopublic.com\/viajestravelandcostaricasa\/form\/InquiryForm\/formperma\/5m5hrLu4jRDezpnhRpurdbD_ba_-aE3VU9Pjj9hDwVc?htl=Activity-Name&amp;referrername=El-Refugio-Night-Tour\"><\/iframe>\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6861d1f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6861d1f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6eafd671\" data-id=\"6eafd671\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d305304 elementor-widget elementor-widget-heading\" data-id=\"4d305304\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visitas relacionadas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e12d520 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e12d520\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e302294\" data-id=\"1e302294\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-669eddab elementor-widget elementor-widget-heading\" data-id=\"669eddab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hoteles relacionados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros.<\/p>\n<p>Los animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno.  <\/p>\n<p>El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona.  <\/p>\n<p>Te unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n.<\/p>\n<p>Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.  <\/p>\n","protected":false},"author":1,"featured_media":5212,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"nf_dc_page":"","_angie_page":false,"inline_featured_image":false,"_joinchat":[]},"activity_categories":[109],"activity_types":[100],"activitylocation":[111],"class_list":["post-6508","activities","type-activities","status-publish","format-standard","has-post-thumbnail","hentry","activity_categories-santuario-de-animales","activity_types-naturaleza","activitylocation-bosque-nuboso-de-monteverde"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros. Los animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno. El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona. Te unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n. Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"erick\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Costa Rica Traveland - Costa Rica Travel Agency\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Excursi\u00f3n nocturna a El Refugio - Costa Rica Traveland\" \/>\n\t\t<meta property=\"og:description\" content=\"La Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros. Los animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno. El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona. Te unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n. Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-21T21:45:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-11-20T19:32:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/travelandcostarica\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Excursi\u00f3n nocturna a El Refugio - Costa Rica Traveland\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros. Los animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno. El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona. Te unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n. Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/#listItem\",\"name\":\"Activities\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/#listItem\",\"position\":2,\"name\":\"Activities\",\"item\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/categor\\u00edas-de-actividades\\\/santuario-de-animales\\\/#listItem\",\"name\":\"Santuario de animales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/categor\\u00edas-de-actividades\\\/santuario-de-animales\\\/#listItem\",\"position\":3,\"name\":\"Santuario de animales\",\"item\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/categor\\u00edas-de-actividades\\\/santuario-de-animales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#listItem\",\"name\":\"Excursi\\u00f3n nocturna a El Refugio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/#listItem\",\"name\":\"Activities\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#listItem\",\"position\":4,\"name\":\"Excursi\\u00f3n nocturna a El Refugio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/categor\\u00edas-de-actividades\\\/santuario-de-animales\\\/#listItem\",\"name\":\"Santuario de animales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#organization\",\"name\":\"Costa Rica Traveland\",\"description\":\"Costa Rica Travel Agency\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/\",\"telephone\":\"+50640001623\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-green-no-cr-registered2-1.png\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#organizationLogo\",\"width\":1366,\"height\":768},\"image\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/travelandcostarica\",\"https:\\\/\\\/www.instagram.com\\\/travelandcostarica\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CostaRicaTraveland\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/author\\\/erick\\\/#author\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/author\\\/erick\\\/\",\"name\":\"erick\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e957b602f4a3a2ee03fdf195cad40720cb436739abd1ed23472ad1bb45b2569e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"erick\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#webpage\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/\",\"name\":\"Excursi\\u00f3n nocturna a El Refugio - Costa Rica Traveland\",\"description\":\"La Excursi\\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\\u00fceyas, coat\\u00edes, olingos y kinkajous, as\\u00ed como aves dormidas y una gran variedad de insectos, entre otros. Los animales en Monteverde Costa Rica son m\\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\\u00e1 muchas m\\u00e1s oportunidades de verlos en un tour nocturno. El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\\u00f3n t\\u00edpica, ver\\u00e1 entre 3 y 5 especies de mam\\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\\u00e1 ver en cualquier otra excursi\\u00f3n nocturna de la zona. Te unir\\u00e1s a un grupo de cuatro a seis personas, con un gu\\u00eda local que te dar\\u00e1 una introducci\\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\\u00f3n. Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\\u00f1os menores de 5 a\\u00f1os.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/author\\\/erick\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/author\\\/erick\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/El-Refugio-Night-Tour-1.jpg\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#mainImage\",\"width\":2048,\"height\":1365},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/activities\\\/excursion-nocturna-a-el-refugio\\\/#mainImage\"},\"datePublished\":\"2023-09-21T21:45:35+00:00\",\"dateModified\":\"2023-11-20T19:32:18+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/\",\"name\":\"Costa Rica Traveland\",\"description\":\"Costa Rica Travel Agency\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/costaricatraveland.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Excursi\u00f3n nocturna a El Refugio - Costa Rica Traveland","description":"La Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros. Los animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno. El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona. Te unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n. Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.","canonical_url":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/costaricatraveland.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/activities\/#listItem","name":"Activities"}},{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/activities\/#listItem","position":2,"name":"Activities","item":"https:\/\/costaricatraveland.com\/es\/activities\/","nextItem":{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/categor\u00edas-de-actividades\/santuario-de-animales\/#listItem","name":"Santuario de animales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/categor\u00edas-de-actividades\/santuario-de-animales\/#listItem","position":3,"name":"Santuario de animales","item":"https:\/\/costaricatraveland.com\/es\/categor\u00edas-de-actividades\/santuario-de-animales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#listItem","name":"Excursi\u00f3n nocturna a El Refugio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/activities\/#listItem","name":"Activities"}},{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#listItem","position":4,"name":"Excursi\u00f3n nocturna a El Refugio","previousItem":{"@type":"ListItem","@id":"https:\/\/costaricatraveland.com\/es\/categor\u00edas-de-actividades\/santuario-de-animales\/#listItem","name":"Santuario de animales"}}]},{"@type":"Organization","@id":"https:\/\/costaricatraveland.com\/es\/#organization","name":"Costa Rica Traveland","description":"Costa Rica Travel Agency","url":"https:\/\/costaricatraveland.com\/es\/","telephone":"+50640001623","logo":{"@type":"ImageObject","url":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png","@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#organizationLogo","width":1366,"height":768},"image":{"@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/travelandcostarica","https:\/\/www.instagram.com\/travelandcostarica\/","https:\/\/www.youtube.com\/@CostaRicaTraveland"]},{"@type":"Person","@id":"https:\/\/costaricatraveland.com\/es\/author\/erick\/#author","url":"https:\/\/costaricatraveland.com\/es\/author\/erick\/","name":"erick","image":{"@type":"ImageObject","@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e957b602f4a3a2ee03fdf195cad40720cb436739abd1ed23472ad1bb45b2569e?s=96&d=mm&r=g","width":96,"height":96,"caption":"erick"}},{"@type":"WebPage","@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#webpage","url":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/","name":"Excursi\u00f3n nocturna a El Refugio - Costa Rica Traveland","description":"La Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros. Los animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno. El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona. Te unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n. Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/costaricatraveland.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#breadcrumblist"},"author":{"@id":"https:\/\/costaricatraveland.com\/es\/author\/erick\/#author"},"creator":{"@id":"https:\/\/costaricatraveland.com\/es\/author\/erick\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2023\/07\/El-Refugio-Night-Tour-1.jpg","@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#mainImage","width":2048,"height":1365},"primaryImageOfPage":{"@id":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/#mainImage"},"datePublished":"2023-09-21T21:45:35+00:00","dateModified":"2023-11-20T19:32:18+00:00"},{"@type":"WebSite","@id":"https:\/\/costaricatraveland.com\/es\/#website","url":"https:\/\/costaricatraveland.com\/es\/","name":"Costa Rica Traveland","description":"Costa Rica Travel Agency","inLanguage":"es-ES","publisher":{"@id":"https:\/\/costaricatraveland.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Costa Rica Traveland - Costa Rica Travel Agency","og:type":"article","og:title":"Excursi\u00f3n nocturna a El Refugio - Costa Rica Traveland","og:description":"La Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros. Los animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno. El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona. Te unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n. Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.","og:url":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/","og:image":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png","og:image:secure_url":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png","og:image:width":1366,"og:image:height":768,"article:published_time":"2023-09-21T21:45:35+00:00","article:modified_time":"2023-11-20T19:32:18+00:00","article:publisher":"https:\/\/www.facebook.com\/travelandcostarica","twitter:card":"summary","twitter:title":"Excursi\u00f3n nocturna a El Refugio - Costa Rica Traveland","twitter:description":"La Excursi\u00f3n Nocturna El Refugio es un paseo ligero de 2 horas en busca de las criaturas de la noche, recomendado a todo aquel que quiera ver animales salvajes como perezosos, armadillos, puercoespines, zarig\u00fceyas, coat\u00edes, olingos y kinkajous, as\u00ed como aves dormidas y una gran variedad de insectos, entre otros. Los animales en Monteverde Costa Rica son m\u00e1s activos y prominentes durante la noche cuando salen en busca de comida y refugio, por lo que tendr\u00e1 muchas m\u00e1s oportunidades de verlos en un tour nocturno. El Refugio es un lugar privilegiado para observar especies de aves como quetzales, motmots y tucanes; animales terrestres como monos, coat\u00edes, olingos, perezosos, ranas, serpientes y una gran variedad de insectos. En una excursi\u00f3n t\u00edpica, ver\u00e1 entre 3 y 5 especies de mam\u00edferos, entre 5 y 10 especies de aves, un par de serpientes o ranas y muchos tipos de insectos. Se trata de la mayor variedad de animales que podr\u00e1 ver en cualquier otra excursi\u00f3n nocturna de la zona. Te unir\u00e1s a un grupo de cuatro a seis personas, con un gu\u00eda local que te dar\u00e1 una introducci\u00f3n y linternas antes de comenzar la caminata por los senderos de El Refugio. Las plazas son limitadas, por lo que es necesario reservar con antelaci\u00f3n. Restricciones: El Refugio Night Tour no es accesible en silla de ruedas, y no es adecuado para ni\u00f1os menores de 5 a\u00f1os.","twitter:image":"https:\/\/costaricatraveland.com\/wp-content\/uploads\/2021\/07\/logo-green-no-cr-registered2-1.png"},"aioseo_meta_data":{"post_id":"6508","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-09-21 21:45:38","updated":"2025-06-04 04:41:23","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/costaricatraveland.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/costaricatraveland.com\/es\/activities\/\" title=\"Activities\">Activities<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/costaricatraveland.com\/es\/categor\u00edas-de-actividades\/santuario-de-animales\/\" title=\"Santuario de animales\">Santuario de animales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tExcursi\u00f3n nocturna a El Refugio\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/costaricatraveland.com\/es\/"},{"label":"Activities","link":"https:\/\/costaricatraveland.com\/es\/activities\/"},{"label":"Santuario de animales","link":"https:\/\/costaricatraveland.com\/es\/categor\u00edas-de-actividades\/santuario-de-animales\/"},{"label":"Excursi\u00f3n nocturna a El Refugio","link":"https:\/\/costaricatraveland.com\/es\/activities\/excursion-nocturna-a-el-refugio\/"}],"_links":{"self":[{"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/activities\/6508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/activities"}],"about":[{"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/types\/activities"}],"author":[{"embeddable":true,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/activities\/6508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/media\/5212"}],"wp:attachment":[{"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/media?parent=6508"}],"wp:term":[{"taxonomy":"activity_categories","embeddable":true,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/activity_categories?post=6508"},{"taxonomy":"activity_types","embeddable":true,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/activity_types?post=6508"},{"taxonomy":"activitylocation","embeddable":true,"href":"https:\/\/costaricatraveland.com\/es\/wp-json\/wp\/v2\/activitylocation?post=6508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}